{"id":7860,"date":"2023-07-17T17:26:00","date_gmt":"2023-07-17T17:26:00","guid":{"rendered":"https:\/\/kaweska.fr\/?p=7860"},"modified":"2023-10-04T18:18:04","modified_gmt":"2023-10-04T18:18:04","slug":"prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme","status":"publish","type":"post","link":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/","title":{"rendered":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7860\" class=\"elementor elementor-7860\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-74d743d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74d743d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9808c70\" data-id=\"9808c70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7e0821 elementor-widget elementor-widget-text-editor\" data-id=\"e7e0821\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La loi portant mesures d\u2019urgence pour la protection du pouvoir d\u2019achat du 18\u00a0ao\u00fbt\u00a02022 avait instaur\u00e9 pour les PME et jusqu&rsquo;au 1er\u00a0trimestre\u00a02023 un plafonnement \u00e0 3,5\u00a0% de l\u2019\u00e9volution annuelle de l\u2019indice des loyers commerciaux\u00a0(ILC). Ce dispositif avait par exemple permis aux PME dont le bail commercial pr\u00e9voyait une indexation au 1<sup>er<\/sup> trimestre 2023 de limiter la hausse de loyer \u00e0 3,5% au lieu de 6,69%.<\/p><p>Ce plafonnement est prolong\u00e9 d\u2019un an soit jusqu\u2019au 31 mars 2024 par une loi du 7 juillet 2023.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d8a0353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8a0353\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b2edb51\" data-id=\"b2edb51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c127303 elementor-widget elementor-widget-image\" data-id=\"c127303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1566\" height=\"1044\" src=\"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg\" class=\"attachment-large size-large wp-image-7866\" alt=\"\" srcset=\"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg 1566w, https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23-1536x1024.jpg 1536w\" sizes=\"(max-width: 1566px) 100vw, 1566px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-2e43ba1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e43ba1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1722574\" data-id=\"1722574\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfc43dc elementor-widget elementor-widget-heading\" data-id=\"dfc43dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p><b><span style=\"font-size:16.0pt;line-height:107%\">Un plafonnement temporaire reconduit pour une ann\u00e9e suppl\u00e9mentaire<\/span><\/b><span style=\"color: var(--theme-heading-font-color);font-size: var(--theme-h2-font-size);font-weight: var(--theme-heading-font-weight);background-color: var(--theme-body-bg-color)\"><\/span><\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-71f82e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71f82e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-affc72b\" data-id=\"affc72b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbe2384 elementor-widget elementor-widget-text-editor\" data-id=\"fbe2384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: var(--theme-body-bg-color); color: var(--theme-body-font-color);\">La prolongation temporaire du plafonnement de la variation de l\u2019ILC vise \u00e0 r\u00e9pondre au contexte actuel d\u2019inflation toujours tr\u00e8s \u00e9lev\u00e9. Elle s\u2019applique une ann\u00e9e suppl\u00e9mentaire soit jusqu\u2019au 1er trimestre 2024. Elle concerne donc 4 indices : le 2\u00e8me trimestre 2023, le 3\u00e8me trimestre 2023, le 4\u00e8me trimestre 2023 et le 1er trimestre 2024, qui seront respectivement publi\u00e9s en septembre 2023, d\u00e9cembre 2023, mars 2024 et juin 2024.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-005b3e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"005b3e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f4a0b6\" data-id=\"0f4a0b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7b7475 elementor-widget elementor-widget-heading\" data-id=\"a7b7475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p><b><span style=\"font-size:16.0pt;line-height:107%\">Les entreprises \u00e9ligibles sont les PME au sens du droit europ\u00e9en dont les baux commerciaux pr\u00e9voient une r\u00e9vision du loyer index\u00e9e sur l'ILC<\/span><\/b><span style=\"color: var(--theme-heading-font-color);font-size: var(--theme-h2-font-size);font-weight: var(--theme-heading-font-weight);background-color: var(--theme-body-bg-color)\"><\/span><\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-78ff53d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78ff53d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72d83c6\" data-id=\"72d83c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f331c3f elementor-widget elementor-widget-text-editor\" data-id=\"f331c3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"background-color: var(--theme-body-bg-color); color: var(--theme-body-font-color);\">La mesure s\u2019applique aux PME au sens du droit europ\u00e9en. Il s\u2019agit des entreprises qui occupent moins de 250 personnes et dont le chiffre d&rsquo;affaires annuel n&rsquo;exc\u00e8de pas 50 millions d\u2019euros ou dont le total du bilan annuel n&rsquo;exc\u00e8de pas 43 millions d\u2019euros.<\/span><\/p><p>Les PME \u00e9ligibles doivent justifier d\u2019un bail commercial dont les r\u00e9visions de loyers sont encadr\u00e9es par l\u2019indice trimestriel des loyers commerciaux. Le plafonnement intervient alors :<\/p><ul><li>Pour les r\u00e9visions automatiques (ou \u00ab conventionnelles \u00bb) dans le cadre de l\u2019application d\u2019une clause d\u2019\u00e9chelle mobile, au vu du trimestre sur lequel la revalorisation annuelle est adoss\u00e9e et qui est compris entre le 2\u00e8me trimestre 2023 et le 1er trimestre 2024 ;<\/li><li>Pour le calcul du plafonnement des r\u00e9visions triennales (ou \u00ab l\u00e9gale \u00bb) demand\u00e9e par l\u2019une des parties (bailleur ou preneur), se basant sur un indice des loyers commerciaux \u00e0 compter du 2\u00e8me trimestre 2023 ;<\/li><li>Pour le calcul du plafonnement de la r\u00e9vision du loyer \u00e0 l\u2019occasion du renouvellement de bail se basant sur un indice des loyers commerciaux \u00e0 compter du 2\u00e8me trimestre 2023.<\/li><\/ul><p>A noter toutefois que le plafonnement de l\u2019ILC ne s\u2019applique pas en cas de changement d\u2019activit\u00e9 (appel\u00e9e d\u00e9sp\u00e9cialisation) ou de modification mat\u00e9rielle des facteurs locaux de commercialit\u00e9. Il\u00a0ne s\u2019applique pas non plus aux contrats dont les r\u00e9visions de loyer sont encadr\u00e9es par d\u2019autres indices (indice des co\u00fbts \u00e0 la construction ou indice des loyers des activit\u00e9s tertiaires).<span style=\"background-color: var(--theme-body-bg-color); color: var(--theme-body-font-color);\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-62a4ae8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62a4ae8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0a2fac\" data-id=\"b0a2fac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6904ae elementor-widget elementor-widget-heading\" data-id=\"a6904ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p><b><span style=\"font-size:16.0pt;line-height:107%\">Le plafonnement ne peut faire l\u2019objet de mesure de rattrapage par les bailleurs<\/span><\/b><span style=\"background-color: var(--theme-body-bg-color);color: var(--theme-heading-font-color);font-size: var(--theme-h2-font-size);font-weight: var(--theme-heading-font-weight)\"><\/span><\/p><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-74e3df9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74e3df9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8b66cd\" data-id=\"e8b66cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d326de9 elementor-widget elementor-widget-text-editor\" data-id=\"d326de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le plafonnement est d\u00e9finitivement acquis. La majoration ou la diminution de loyer cons\u00e9cutive \u00e0 une r\u00e9vision post\u00e9rieure ne peut prendre en compte la part de variation de l&rsquo;indice des loyers commerciaux sup\u00e9rieure \u00e0 3,5 % sur cette m\u00eame p\u00e9riode. Concr\u00e8tement, cela signifie que, si la revalorisation annuelle est de 3,5 % (au lieu de 5,5 %) du fait du plafonnement, le bailleur, l\u2019ann\u00e9e suivante, ne pourra pas ajouter \u00e0 la revalorisation les 2 % qui ont \u00e9t\u00e9 \u00e9cr\u00eat\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-4304011 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4304011\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-093ef52\" data-id=\"093ef52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La loi portant mesures d\u2019urgence pour la protection du pouvoir d\u2019achat du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7866,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,107],"tags":[],"class_list":["post-7860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislation","category-optimisation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA\" \/>\n<meta property=\"og:description\" content=\"La loi portant mesures d\u2019urgence pour la protection du pouvoir d\u2019achat du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/\" \/>\n<meta property=\"og:site_name\" content=\"KAWESKA\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-17T17:26:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T18:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1566\" \/>\n\t<meta property=\"og:image:height\" content=\"1044\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kaweska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kaweska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/\"},\"author\":{\"name\":\"Kaweska\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/#\\\/schema\\\/person\\\/b7b92b44b877ee069a5dd075016a8299\"},\"headline\":\"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME\",\"datePublished\":\"2023-07-17T17:26:00+00:00\",\"dateModified\":\"2023-10-04T18:18:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kaweska.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Article-17.07.23.jpg\",\"articleSection\":[\"LEGISLATION\",\"OPTIMISATION\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/\",\"url\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/\",\"name\":\"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kaweska.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Article-17.07.23.jpg\",\"datePublished\":\"2023-07-17T17:26:00+00:00\",\"dateModified\":\"2023-10-04T18:18:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/#\\\/schema\\\/person\\\/b7b92b44b877ee069a5dd075016a8299\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kaweska.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Article-17.07.23.jpg\",\"contentUrl\":\"https:\\\/\\\/kaweska.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Article-17.07.23.jpg\",\"width\":1566,\"height\":1044},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/2023\\\/07\\\/17\\\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/kaweska.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/#website\",\"url\":\"https:\\\/\\\/kaweska.fr\\\/\",\"name\":\"KAWESKA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kaweska.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kaweska.fr\\\/#\\\/schema\\\/person\\\/b7b92b44b877ee069a5dd075016a8299\",\"name\":\"Kaweska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g\",\"caption\":\"Kaweska\"},\"url\":\"https:\\\/\\\/kaweska.fr\\\/index.php\\\/author\\\/gutton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/","og_locale":"fr_FR","og_type":"article","og_title":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA","og_description":"La loi portant mesures d\u2019urgence pour la protection du pouvoir d\u2019achat du [&hellip;]","og_url":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/","og_site_name":"KAWESKA","article_published_time":"2023-07-17T17:26:00+00:00","article_modified_time":"2023-10-04T18:18:04+00:00","og_image":[{"width":1566,"height":1044,"url":"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg","type":"image\/jpeg"}],"author":"Kaweska","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Kaweska","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#article","isPartOf":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/"},"author":{"name":"Kaweska","@id":"https:\/\/kaweska.fr\/#\/schema\/person\/b7b92b44b877ee069a5dd075016a8299"},"headline":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME","datePublished":"2023-07-17T17:26:00+00:00","dateModified":"2023-10-04T18:18:04+00:00","mainEntityOfPage":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#primaryimage"},"thumbnailUrl":"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg","articleSection":["LEGISLATION","OPTIMISATION"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/","url":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/","name":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME - KAWESKA","isPartOf":{"@id":"https:\/\/kaweska.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#primaryimage"},"image":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#primaryimage"},"thumbnailUrl":"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg","datePublished":"2023-07-17T17:26:00+00:00","dateModified":"2023-10-04T18:18:04+00:00","author":{"@id":"https:\/\/kaweska.fr\/#\/schema\/person\/b7b92b44b877ee069a5dd075016a8299"},"breadcrumb":{"@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#primaryimage","url":"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg","contentUrl":"https:\/\/kaweska.fr\/wp-content\/uploads\/2023\/10\/Article-17.07.23.jpg","width":1566,"height":1044},{"@type":"BreadcrumbList","@id":"https:\/\/kaweska.fr\/index.php\/2023\/07\/17\/prolongement-jusquau-31-mars-2024-du-plafonnement-a-35-de-la-hausse-des-loyers-commerciaux-pour-les-pme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kaweska.fr\/"},{"@type":"ListItem","position":2,"name":"Prolongement jusqu\u2019au 31 mars 2024 du plafonnement \u00e0 3,5% de la hausse des loyers commerciaux pour les PME"}]},{"@type":"WebSite","@id":"https:\/\/kaweska.fr\/#website","url":"https:\/\/kaweska.fr\/","name":"KAWESKA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kaweska.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/kaweska.fr\/#\/schema\/person\/b7b92b44b877ee069a5dd075016a8299","name":"Kaweska","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/283cc322b641c4a76be875add345feb445fc20facef9fff1e304618085a1960e?s=96&d=mm&r=g","caption":"Kaweska"},"url":"https:\/\/kaweska.fr\/index.php\/author\/gutton\/"}]}},"_links":{"self":[{"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/posts\/7860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7860"}],"version-history":[{"count":0,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/posts\/7860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/media\/7866"}],"wp:attachment":[{"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kaweska.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}